{"id":14438,"date":"2020-10-27T05:00:00","date_gmt":"2020-10-27T04:00:00","guid":{"rendered":"https:\/\/dev.goodata.eu\/carbon-footprint-organizzazione-rendicontare-le-emissioni-di-gas-serra-con-la-iso-14064\/"},"modified":"2024-10-02T14:53:13","modified_gmt":"2024-10-02T12:53:13","slug":"carbon-footprint-organizzazione-rendicontare-le-emissioni-di-gas-serra-con-la-iso-14064","status":"publish","type":"post","link":"https:\/\/www.goodata.eu\/en\/blog\/sustainability-2\/carbon-footprint-organizzazione-rendicontare-le-emissioni-di-gas-serra-con-la-iso-14064\/","title":{"rendered":"Carbon Footprint Organizzazione: rendicontare le emissioni di gas serra con la ISO 14064"},"content":{"rendered":"<p><b>Come e perch\u00e9 avviare in azienda un percorso virtuoso, all\u2019insegna della sostenibilit\u00e0.<\/b><\/p>\n<p>&nbsp;<\/p>\n<p>Le aziende che scelgono di acquisire la certificazione carbon footprint \u2013 calcolando e comunicando al pubblico l\u2019entit\u00e0 delle proprie emissioni di gas serra \u2013 ottengono numerosi vantaggi. L\u2019impegno ambientale, infatti, viene premiato, dai consumatori e non solo; ecco come sviluppare l\u2019inventario delle emissioni GHG e perch\u00e9 \u00e8 importante.<\/p>\n<p>&nbsp;<\/p>\n<h2>Carbon Footprint Organizzazione: un inventario per contrastare i cambiamenti climatici<\/h2>\n<p>&nbsp;<\/p>\n<p>Per rendicontare le emissioni di gas ad effetto serra e fornire informazioni dettagliate a stakeholder e consumatori attenti alle performance ambientali delle imprese, oggi molte aziende scelgono di calcolare la propria impronta di carbonio.<\/p>\n<p>&nbsp;<\/p>\n<p>Con la carbon footprint, un\u2019azienda \u2013 ma anche un sito produttivo, un gruppo societario o un singolo cantiere \u2013 pu\u00f2 <b>quantificare la totalit\u00e0 delle emissioni di gas ad effetto serra (GHG) <\/b>mediante un approccio di tipo inventariale.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Cosa significa?<\/b><\/p>\n<p>&nbsp;<\/p>\n<p>Che se per misurare l\u2019impronta di carbonio di un prodotto viene analizzato l\u2019intero ciclo di vita del bene, nel caso delle organizzazioni si procede con la redazione dell\u2019inventario delle emissioni di GHG, considerando quelle dirette, indirette da consumo energetico e altre emissioni indirette.<\/p>\n<p>&nbsp;<\/p>\n<p>Pertanto, l\u2019azienda che intende definire la propria impronta di carbonio e certificarsi, deve<b> rispettare quanto precisato dalla norma tecnica internazionale ISO 14064<\/b> e provvedere:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Alla realizzazione dell\u2019inventario dei GHG (Greenhouses Gases \u2013 gas ad effetto serra)<\/li>\n<li>Alla definizione della procedura di gestione relativa ai dati acquisiti<\/li>\n<li>Alla redazione del report dei GHG da destinare al pubblico<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3>ISO 14064 E CFO: sviluppare, progettare e rendicontare con la norma internazionale<\/h3>\n<p>&nbsp;<\/p>\n<p>La ISO 14064:2019 \u00e8 la norma internazionale che specifica i principi e i requisiti necessari alla quantificazione e alla rendicontazione delle emissioni di gas serra di un\u2019organizzazione.<br \/>\nLa norma supporta lo sviluppo dell\u2019inventario delle emissioni di GHG, la gestione dei progetti volti alla riduzione\/eliminazione delle emissioni e aiuta l\u2019azienda a rendicontare e validare quanto rilevato.<\/p>\n<p>&nbsp;<\/p>\n<p><b>La norma ISO 14064 \u00e8 composta da tre parti,<\/b> che possono essere usate anche separatamente.<\/p>\n<p>La prima \u00e8 dedicata ai principi e ai requisiti utili alla progettazione e allo sviluppo degli inventari di gas serra, incluso i parametri necessari alla definizione dei confini di emissione dei GHG.<\/p>\n<p>&nbsp;<\/p>\n<p>La seconda parte \u00e8 dedicata ai progetti volti a ridurre\/eliminare le emissioni di gas serra dell\u2019organizzazione. In questa sezione sono presenti tutti i dettagli utili a definire il progetto, monitorare, quantificare e rendicontare i dati.<\/p>\n<p>&nbsp;<\/p>\n<p>La terza parte \u00e8 dedicata alla verifica di quanto rilevato in merito alle emissioni di GHG.<\/p>\n<p>&nbsp;<\/p>\n<h3>Certificazione Carbon Footprint Organizzazione: perch\u00e9 conviene alle aziende?<\/h3>\n<p>&nbsp;<\/p>\n<p>Le aziende che conseguono la certificazione carbon footprint ottengono numerosi vantaggi.<\/p>\n<p>Sul piano operativo, l\u2019organizzazione riesce a <b>identificare le sorgenti massive e l\u2019intensit\u00e0 delle emissioni di gas serra relative alle attivit\u00e0 aziendali <\/b>e pu\u00f2 capire, dunque, se e dove intervenire per fare la propria parte a beneficio dell\u2019ambiente.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019inventario delle emissioni di gas serra sviluppato diventa, inoltre:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Uno strumento efficace per identificare e gestire i rischi relativi ai gas serra<\/li>\n<li>Un dato efficace per definire le politiche aziendali e le prossime strategie di gestione<\/li>\n<li>Un utile baseline per monitorare \u2013 da qui in avanti \u2013 il miglioramento delle performance ambientali dell\u2019azienda<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Sul piano comunicativo, invece, l\u2019azienda ha la possibilit\u00e0 di <b>coinvolgere e informare stakeholder interni ed esterni<\/b> circa le performance ambientali dell\u2019organizzazione.<br \/>\nCi\u00f2 contribuisce a:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Migliorare la green reputation<\/li>\n<li>Stuzzicare l\u2019interesse dei consumatori e della PA<\/li>\n<li>Sostenere la Corporate Social Responsability (CSR)<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3>Carbon Footprint di Organizzazione: il processo virtuoso che ti offre Tecno<\/h3>\n<p>&nbsp;<\/p>\n<p><b>L\u2019impegno ambientale delle aziende viene premiato. <\/b>Vuoi sapere in che modo?<\/p>\n<p>&nbsp;<\/p>\n<p>Oggi i consumatori tendono a preferire i prodotti e\/o i servizi offerti da aziende che hanno un approccio green. La pubblica amministrazione, cos\u00ec come gli enti locali, privilegiano le organizzazioni e le imprese dotate di certificazioni ambientali, riservando loro l\u2019accesso facilitato a bandi, appalti e gare di fornitura.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00c8 per queste ragioni che il nostro team ha scelto di accompagnare le organizzazioni interessate alla certificazione carbon footprint in ci\u00f2 che \u00e8 stato pi\u00f9 volte definito un <b>\u201cprocesso virtuoso\u201c.<\/b> Un percorso che i nostri ingegneri fanno con l\u2019azienda, la societ\u00e0, l\u2019impresa o il gruppo societario interessato e che si concretizza mediante diverse fasi.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Step One:<\/b> la parola d\u2019ordine di questa fase \u00e8 consapevolezza. Aiutiamo l\u2019azienda a calcolare l\u2019impronta di carbonio nel rispetto degli standard ISO di riferimento. Gestione, conoscenza e monitoraggio.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Step Two:<\/b> prima di ogni intervento c\u2019\u00e8 un progetto, una struttura. \u00c8 in questo momento che il rinnovamento e l\u2019ottimizzazione delle prestazioni ambientali, dei consumi e delle emissioni di gas serra viene strutturato, considerando tutte le implementazioni e le azioni possibili.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Step Three: <\/b>mettiamo a disposizione dell\u2019organizzazione un software di monitoraggio per agevolare la consultazione futura dei dati e la definizione delle prossime strategie aziendali.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Vuoi ottenere la certificazione carbon footprint per la tua azienda? <\/b>Lasciaci i tuoi dati.<\/p>\n<p>&nbsp;<\/p>\n<p>Ti contatteremo per una prima consulenza gratuita.<\/p>","protected":false},"excerpt":{"rendered":"<p>Come e perch\u00e9 avviare in azienda un percorso virtuoso, all\u2019insegna della sostenibilit\u00e0. &nbsp; Le aziende che scelgono di acquisire la certificazione carbon footprint \u2013 calcolando e comunicando al pubblico l\u2019entit\u00e0 delle proprie emissioni di gas serra \u2013 ottengono numerosi vantaggi. L\u2019impegno ambientale, infatti, viene premiato, dai consumatori e non solo; ecco come sviluppare l\u2019inventario delle [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14441,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-14438","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sostenibilita"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/posts\/14438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/comments?post=14438"}],"version-history":[{"count":0,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/posts\/14438\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/media\/14441"}],"wp:attachment":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/media?parent=14438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/categories?post=14438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/tags?post=14438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}