{"id":14510,"date":"2020-04-21T06:00:00","date_gmt":"2020-04-21T04:00:00","guid":{"rendered":"https:\/\/dev.goodata.eu\/gestione-produzione-industriale-lottimizzazione-generata-dalla-diagnosi-delle-risorse\/"},"modified":"2024-10-03T12:06:51","modified_gmt":"2024-10-03T10:06:51","slug":"gestione-produzione-industriale-lottimizzazione-generata-dalla-diagnosi-delle-risorse","status":"publish","type":"post","link":"https:\/\/www.goodata.eu\/en\/blog\/sustainability-2\/gestione-produzione-industriale-lottimizzazione-generata-dalla-diagnosi-delle-risorse\/","title":{"rendered":"Gestione produzione industriale: l\u2019ottimizzazione generata dalla diagnosi delle risorse"},"content":{"rendered":"<p><b>Come ridurre il consumo delle risorse aziendali attraverso la diagnosi delle risorse e l\u2019impiego di beni strumentali.<\/b><\/p>\n<p>&nbsp;<\/p>\n<p>ENEA propone una metodologia per l\u2019analisi delle risorse e dei materiali impiegati nei processi produttivi. \u00c8 possibile ridurre il consumo delle risorse e ottimizzare il rendimento e i risparmi di un\u2019impresa attraverso la valorizzazione di risorse, materiali e scarti aziendali? Certo che s\u00ec!<\/p>\n<p>&nbsp;<\/p>\n<h2>Diagnosi delle risorse: cos\u2019\u00e8 e a cosa serve<\/h2>\n<p>&nbsp;<\/p>\n<p>La diagnosi delle risorse \u00e8 uno strumento che analizza le risorse e i materiali impiegati da un\u2019impresa nei processi produttivi. Serve ad efficientare l\u2019uso e la gestione delle risorse, a monitorarne l\u2019impiego e a ridurne il consumo.<\/p>\n<p>&nbsp;<\/p>\n<p>Si tratta di uno strumento volontario, in quanto \u2013 ad oggi \u2013 non esiste alcun obbligo normativo che vincoli le imprese ad effettuare la diagnosi delle risorse; a differenza di quanto avviene per la diagnosi energetica. Eppure <b>effettuare la diagnosi delle risorse rappresenterebbe per le imprese una vera opportunit\u00e0, <\/b>perch\u00e9 capace di generare benefici economici, sociali e ambientali, importanti per le singole realt\u00e0 industriali, ma anche per il territorio e la collettivit\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<p>Infatti, con la diagnosi delle risorse le imprese potrebbero: contabilizzare le risorse impiegate nei processi produttivi o in singole attivit\u00e0; elaborare un piano di efficientamento (che include la diagnosi energetica) e adottare una strategia per competere in maniera efficace sul mercato.<\/p>\n<p>&nbsp;<\/p>\n<p>Data l\u2019assenza di metodi o linee guida per eseguire la diagnosi delle risorse, ENEA (Agenzia nazionale per le nuove tecnologie, l\u2019energia e lo sviluppo sostenibile) ha proposto una metodologia realizzata per il progetto Proper Umbria.<\/p>\n<p>&nbsp;<\/p>\n<h2>ENEA e Proper Umbria: diagnosi delle risorse e valorizzazione degli scarti aziendali come capisaldi dell\u2019economia circolare<\/h2>\n<p>&nbsp;<\/p>\n<p>The ESG <i>progetto Proper Umbria<\/i> propone una metodologia per incrementare il riutilizzo degli scarti aziendali basandosi sulla mappatura delle materie prime e dei materiali usati nei processi produttivi e sulla diagnosi delle risorse.<\/p>\n<p>&nbsp;<\/p>\n<p>Il progetto \u00e8 stato realizzato in collaborazione con Sviluppumbria e la multinazionale Meccanotecnica Umbria. <b>La metodologia proposta da ENEA prevede quattro fasi:<\/b><\/p>\n<p>&nbsp;<\/p>\n<p><b>1\u00b0 fase \u2013 raccolta dei dati:<\/b> in questa fase vanno raccolti i dati circa le risorse impiegate dall\u2019impresa, sia input (acqua, materie prime, energia, ecc.) sia output (prodotti, sottoprodotti, rifiuti, emissioni, servizi, ecc.). I processi produttivi diventano oggetto di analisi per raccogliere informazioni circa: tipologia delle risorse impiegate, modalit\u00e0 di gestione e di destinazione delle stesse.<\/p>\n<p>&nbsp;<\/p>\n<p><b>2\u00b0 fase \u2013 individuazione delle pratiche: <\/b>in questa fase bisogna individuare le giuste pratiche atte a ridurre il consumo delle risorse ed efficientarne l\u2019utilizzo. Lo studio deve comprendere sia l\u2019eventuale implementazione di nuove pratiche aziendali interne \u2013 mediante l\u2019impiego di percorsi innovativi e sostenibili \u2013 sia nuovi approcci cooperativi e scambi tra aziende \u2013 attraverso l\u2019adozione di percorsi di simbiosi industriale.<\/p>\n<p>&nbsp;<\/p>\n<p><b>3\u00b0 fase \u2013 analisi: <\/b>in questa fase vanno analizzati gli elementi di fattibilit\u00e0 tecnico-economica, gli impatti ambientali e il rispetto di vincoli normativi delle opzioni individuate per la valorizzazione delle risorse. L\u2019analisi di fattibilit\u00e0 tecnico-economica considera: i costi e i ricavi derivati dai processi produttivi e dalla gestione delle risorse esistenti in azienda, e quelli derivanti dall\u2019eventuale implementazione di nuovi percorsi. Per l\u2019analisi degli impatti ambientali, invece, si tiene conto dei parametri definiti dai metodi ISO LCA.<\/p>\n<p>&nbsp;<\/p>\n<p><b>4\u00b0 fase \u2013 redazione dei manuali:<\/b> \u00e8 la fase finale, dedicata alla produzione di manuali operativi secondo le informazioni raccolte e le analisi effettuate, al fine di guidare le imprese verso un uso pi\u00f9 efficiente delle risorse in tutte le fasi di attuazione.<\/p>\n<p>&nbsp;<\/p>\n<p>Il metodo proposto da ENEA mira a valorizzare le risorse impiegate nel processo produttivo e non solo; altro elemento cardine di questa metodologia infatti \u00e8 la <b>valorizzazione degli scarti aziendali.<\/b> Cosa significa? Che gli scarti aziendali possono diventare sottoprodotti da vendere ad altre imprese, capaci di re-indirizzarli. \u00c8 sottoprodotto ci\u00f2 che diventa riutilizzabile, nel rispetto delle norme e senza arrecare danno all\u2019ambiente.<\/p>\n<p>&nbsp;<\/p>\n<p>Il progetto Proper Umbria propone una politica aziendale basata sull\u2019economia circolare e sulla simbiosi industriale.<\/p>\n<p>&nbsp;<\/p>\n<h2>Monitoraggio della produzione industriale: facciamolo con beni strumentali<\/h2>\n<p>&nbsp;<\/p>\n<p>L\u2019ottimizzazione del consumo energetico e delle risorse sono, oggi pi\u00f9 che mai, elementi da considerare come leve strategiche per la ripresa delle imprese nazionali.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00c8 essenziale adottare beni strumentali capaci di monitorare il consumo energetico di un sito produttivo e di singoli impianti di produzione, al fine di definire un piano di efficientamento e ottenere un risparmio economico. Altrettanto fondamentale \u00e8 la possibilit\u00e0 di analizzare le materie immesse negli impianti di produzione, quantificare i prodotti finiti e gli scarti aziendali al fine di ottimizzare l\u2019intero processo produttivo. \u00c8 questa la strada da perseguire per raggiungere il successo e il risparmio economico:<b> adottare strumenti tecnologicamente avanzati utili all\u2019analisi completa dei siti produttivi.<\/b><\/p>\n<p>&nbsp;<\/p>\n<p><i>KontrolON project<\/i> \u00e8 il sistema di monitoraggio degli impianti di produzione che i nostri ingegneri hanno realizzato al fine di supportare l\u2019attivit\u00e0 di imprenditori, responsabili di reparto e commercianti. Un bene che le aziende possono acquistare godendo delle agevolazioni offerte dallo Stato perch\u00e9 compatibile anche con il credito d\u2019imposta 2020.<\/p>\n<p>&nbsp;<\/p>\n<p>Visita il sito web di kontrolON per conoscere tutte le sue funzioni e contattaci se vuoi saperne di pi\u00f9. \u00e8 il sistema di monitoraggio degli impianti di produzione che i nostri ingegneri hanno realizzato al fine di supportare l\u2019attivit\u00e0 di imprenditori, responsabili di reparto e commercianti. Un bene che le aziende possono acquistare godendo delle agevolazioni offerte dallo Stato perch\u00e9 <b>compatibile anche con il credito d\u2019imposta 2020-2021-2022.<\/b><\/p>\n<p>&nbsp;<\/p>\n<p><b>Per scoprire tutte le funzioni del nostro sistema di monitoraggio industriale compila il form.<\/b><\/p>","protected":false},"excerpt":{"rendered":"<p>Come ridurre il consumo delle risorse aziendali attraverso la diagnosi delle risorse e l\u2019impiego di beni strumentali. &nbsp; ENEA propone una metodologia per l\u2019analisi delle risorse e dei materiali impiegati nei processi produttivi. \u00c8 possibile ridurre il consumo delle risorse e ottimizzare il rendimento e i risparmi di un\u2019impresa attraverso la valorizzazione di risorse, materiali [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14513,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-14510","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sostenibilita"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/posts\/14510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/comments?post=14510"}],"version-history":[{"count":0,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/posts\/14510\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/media\/14513"}],"wp:attachment":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/media?parent=14510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/categories?post=14510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/tags?post=14510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}