{"id":14635,"date":"2019-10-15T00:00:00","date_gmt":"2019-10-14T22:00:00","guid":{"rendered":"https:\/\/dev.goodata.eu\/protocollo-itaca-sostenibilita-energetica-e-ambientale-degli-edifici\/"},"modified":"2024-10-03T14:29:07","modified_gmt":"2024-10-03T12:29:07","slug":"protocollo-itaca-sostenibilita-energetica-e-ambientale-degli-edifici","status":"publish","type":"post","link":"https:\/\/www.goodata.eu\/en\/blog\/sustainability-2\/protocollo-itaca-sostenibilita-energetica-e-ambientale-degli-edifici\/","title":{"rendered":"Protocollo Itaca: sostenibilit\u00e0 energetica e ambientale degli edifici"},"content":{"rendered":"<p>In un mercato internazionale sempre pi\u00f9 orientato al \u201cgreen\u201d \u00e8 inevitabile la diffusione del concetto di sostenibilit\u00e0. L\u2019edilizia \u2013 con a seguire settore industriale e trasporti \u2013 \u00e8 quello con maggiore impatto ambientale.<b>\u00a0<\/b>Le strategie nazionali hanno, infatti, come obiettivo la decarbonizzazione del parco immobiliare entro il 2050. La trasformazione da edificio esistente ad edificio ad alte prestazioni energetiche necessita di un\u2019accurata analisi inerente il sistema edificio-impianto.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Il Protocollo ITACA \u00e8 uno strumento di valutazione del livello di sostenibilit\u00e0 energetica e ambientale <\/b>degli edifici che permette di verificarne le prestazioni in riferimento a consumi, efficienza energetica, impatto sull\u2019ambiente e sulla salute dell\u2019uomo.<\/p>\n<p>A tale scopo si favorisce la realizzazione di edifici sempre pi\u00f9 innovativi, a energia zero, puntando a ridotti consumi di acqua, materiali di costruzione che comportino al contempo bassi consumi energetici ed elevato comfort.<\/p>\n<p>&nbsp;<\/p>\n<h2>Protocollo ITACA: il modello italiano per la sostenibilit\u00e0 degli edifici<\/h2>\n<p>&nbsp;<\/p>\n<p>La sostenibilit\u00e0 pu\u00f2 essere articolata in 3 ambiti, cos\u00ec come indicato nella<b> norma ISO 12392<\/b>: economico, sociale, ambientale. Il Protocollo ITACA \u00e8 un sistema di certificazione elaborato dall\u2019Istituto per l\u2018Innovazione e Trasparenza degli Appalti e la Compatibilit\u00e0 ambientale.<\/p>\n<p>&nbsp;<\/p>\n<p>Esso ha un duplice obiettivo:<\/p>\n<ol>\n<li>analizzare le prestazioni di un edificio osservandone i consumi<\/li>\n<li>analizzare l\u2019impatto sull\u2019ambiente e quindi sulla salute dell\u2019uomo<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p>Al termine dell\u2019analisi e della valutazione si ottiene un punteggio che funge da indicatore di qualit\u00e0 dell\u2019edificio o impatto sostenibile raggiunto.<\/p>\n<p>&nbsp;<\/p>\n<h3>Quali sono i punteggi del Protocollo ITACA?<\/h3>\n<p>&nbsp;<\/p>\n<ul>\n<li><span style=\"font-size: medium;\">-1 : Prestazione inferiore allo standard<\/span><\/li>\n<li><span style=\"font-size: medium;\">0: Prestazione minima accettabile definita da leggi e regolamenti vigenti e alla pratica corrente<\/span><\/li>\n<li><span style=\"font-size: medium;\">1: Lieve miglioramento<\/span><\/li>\n<li><span style=\"font-size: medium;\">2: Moderato miglioramento<\/span><\/li>\n<li><span style=\"font-size: medium;\">3: Significativo miglioramento<\/span><\/li>\n<li><span style=\"font-size: medium;\">4: Moderato incremento<\/span><\/li>\n<li><span style=\"font-size: medium;\">5: Prestazione considerevolmente avanzata rispetto alla migliore pratica corrente, di carattere sperimentale<\/span><\/li>\n<\/ul>\n<p><span style=\"font-size: medium;\">\u00a0<\/span><\/p>\n<p><b>Il Protocollo ITACA non \u00e8 uniforme a livello nazionale, <\/b>varia da regione a regione, ci\u00f2 perch\u00e9 vi \u00e8 la necessit\u00e0 di contestualizzare gli interventi. Del resto, un edificio considerato sostenibile in una determinata citt\u00e0 non \u00e8 detto che lo sia allo stesso modo anche in un\u2019altra.<\/p>\n<p>&nbsp;<\/p>\n<h3>Accordo tra Leed e Protocollo ITACA: la certificazione energetica degli edifici<\/h3>\n<p>&nbsp;<\/p>\n<p>Era il 2012 quando si \u00e8 siglato l\u2019accordo tra LEED \u2013 sistema statunitense di classificazione dell\u2019efficienza energetica e impronta ecologica degli edifici \u2013 ed ITACA, in occasione di EIRE, fiera internazionale dell\u2019immobile dedicata al Real Estate. Lo scopo era unificare e rafforzare a livello nazionale i sistemi di accreditamento e certificazione della sostenibilit\u00e0 ambientale delle costruzioni.<\/p>\n<p>&nbsp;<\/p>\n<p>Il Protocollo Itaca \u00e8 basato sullo <b>strumento di valutazione internazionale SBTool <\/b>sviluppato nell\u2019ambito di ricerca Green Building Challenge.<\/p>\n<p>&nbsp;<\/p>\n<p>La certificazione \u00e8 applicabile ai seguenti edifici:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>edifici residenziali<\/li>\n<li>edifici per uffici<\/li>\n<li>edifici commerciali<\/li>\n<li>edifici scolastici<\/li>\n<li>edifici industriali<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>Cos\u2019\u00e8 la certificazione Leed e qual \u00e8 l\u2019obiettivo?<\/h2>\n<p>&nbsp;<\/p>\n<p>La <b>Leed \u2013 Leadership in Energy and Environmental Design <\/b>\u2013 \u00e8 un programma di certificazione volontaria che pu\u00f2 essere applicato sia ad edifici residenziali sia commerciali.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00c8 stato sviluppato dalla U. S. Green Building Council \u2013 USGBC \u2013. Il sistema si basa sull\u2019attribuzione di crediti, la cui somma costituisce il livello di certificazione: <b>Certifies, Silver, Gold, Platinum<\/b> ed \u00e8 riconosciuta a livello internazionale.<\/p>\n<p>&nbsp;<\/p>\n<p>La Leed valuta le prestazioni ambientali dal punto di vista complessivo dell\u2019edificio durante l\u2019intero ciclo di vita: progettazione, costruzione, funzionamento e mira a raggiungere i seguenti scopi:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>definire il concetto di \u201cedificio verde\u201d<\/li>\n<li>promuovere pratiche integrate di progettazione per l\u2019intero edificio<\/li>\n<li>dare un riconoscimento ai leader<\/li>\n<li>stimolare la competizione nello sviluppo di progetti, materiali<\/li>\n<li>aumentare la consapevolezza dei benefici verso la costruzione verde<\/li>\n<li>trasformare il mercato dell\u2019edilizia<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>Diagnosi energetica edifici: sai quanto puoi risparmiare?<\/h2>\n<p>&nbsp;<\/p>\n<p><b>La diagnosi energetica degli edifici \u00e8 un\u2019analisi coordinata del sistema edificio-impianto, <\/b>che individua gli interventi da realizzare, definendo priorit\u00e0, quantificando opportunit\u00e0 di risparmio energetico sotto il profilo costi-benefici.<\/p>\n<p>&nbsp;<\/p>\n<p>La diagnosi energetica deve possedere i seguenti requisiti:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>completezza: descrivere il sistema energetico includendo tutti gli aspetti degli impianti;<\/li>\n<li>attendibilit\u00e0: elaborare dati soddisfacenti dal punto di vista qualitativo e quantitativo necessari all\u2019inventario energetico;<\/li>\n<li>tracciabilit\u00e0: individuare in modo agevole le fonti dei dati, delle modalit\u00e0 di elaborazione dei risultati e delle ipotesi concluse;<\/li>\n<li>utilit\u00e0: identificare e valutare gli interventi di efficienza energetica sotto il profilo costi-benefici;<\/li>\n<li>verificabilit\u00e0: identificare elementi e procedure che consentono la verifica del conseguimento dei miglioramenti di efficienza come risultato degli interventi proposti.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Hai la possibilit\u00e0 di individuare le aree che necessitano di interventi di riqualificazione pi\u00f9 idonei ed efficienti.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Contattaci per saperne di pi\u00f9.<\/b><\/p>","protected":false},"excerpt":{"rendered":"<p>In un mercato internazionale sempre pi\u00f9 orientato al \u201cgreen\u201d \u00e8 inevitabile la diffusione del concetto di sostenibilit\u00e0. L\u2019edilizia \u2013 con a seguire settore industriale e trasporti \u2013 \u00e8 quello con maggiore impatto ambientale.\u00a0Le strategie nazionali hanno, infatti, come obiettivo la decarbonizzazione del parco immobiliare entro il 2050. La trasformazione da edificio esistente ad edificio ad [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14636,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-14635","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sostenibilita"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/posts\/14635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/comments?post=14635"}],"version-history":[{"count":0,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/posts\/14635\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/media\/14636"}],"wp:attachment":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/media?parent=14635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/categories?post=14635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/tags?post=14635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}