{"id":14676,"date":"2019-05-06T00:00:00","date_gmt":"2019-05-05T22:00:00","guid":{"rendered":"https:\/\/dev.goodata.eu\/imprese-energivore-sei-ancora-in-tempo-per-approfittare-delle-agevolazioni\/"},"modified":"2024-10-03T14:43:32","modified_gmt":"2024-10-03T12:43:32","slug":"imprese-energivore-sei-ancora-in-tempo-per-approfittare-delle-agevolazioni","status":"publish","type":"post","link":"https:\/\/www.goodata.eu\/en\/blog\/sustainability-2\/imprese-energivore-sei-ancora-in-tempo-per-approfittare-delle-agevolazioni\/","title":{"rendered":"Imprese energivore: sei ancora in tempo per approfittare delle agevolazioni"},"content":{"rendered":"<p><b>Un dossier che propone la cancellazione dei sussidi alle fonti fossili.\u00a0A rischio finanziamenti e agevolazioni oil &amp; gas.<\/b><\/p>\n<p>&nbsp;<\/p>\n<p>Con l\u2019ultimo dossier sui sussidi alle fonti fossili Legambiente propone la cancellazione e la riduzione degli innumerevoli finanziamenti e sostegni che il governo italiano prevede a beneficio delle aziende italiane che impiegano fonti fossili nella loro attivit\u00e0 produttiva.<\/p>\n<p>&nbsp;<\/p>\n<p>Il Ministero dell\u2019Ambiente ha gi\u00e0 previsto l\u2019aggiornamento del catalogo dei sussidi ambientali entro la fine di giugno dal quale potrebbero essere escluse anche le esenzioni e le riduzioni riconosciute alle aziende energivore. Proviamo a capirne di pi\u00f9.<\/p>\n<p>&nbsp;<\/p>\n<h2>L\u2019oggetto della discordia: i sussidi in favore dell\u2019Oil &amp; Gas<\/h2>\n<p>&nbsp;<\/p>\n<p>A pochi giorni di distanza dall\u2019Earth Day e a seguito delle manifestazioni ambientali che proprio negli ultimi mesi hanno sollevato l\u2019attenzione dell\u2019opinione pubblica, ecco che con l\u2019ultimo dossier sui sussidi ai fossili Legambiente mette in evidenza ci\u00f2 che considera un grande paradosso italiano: si vuole limitare l\u2019inquinamento ambientale, ma allo stesso tempo si sostengono le aziende che fanno uso di sostanze inquinanti.<\/p>\n<p>&nbsp;<\/p>\n<p>Non \u00e8 la prima volta che l\u2019associazione si esprime contro i sussidi alle fonti fossili riconosciuti dallo Stato proponendone riduzione e cancellazione. Ma se per Legambiente questa eliminazione rappresenterebbe una grande opportunit\u00e0 di risparmio in termini economici e in materia di inquinamento, <b>per le aziende che beneficiano di esenzioni e di altri sussidi la proposta di Legambiente provocherebbe la perdita di un sostegno economico essenziale<\/b> per il bilancio aziendale.<\/p>\n<p>&nbsp;<\/p>\n<p>Un elenco molto lungo quello dei sussidi riconosciuti alle aziende utilizzatrici di fonti fossili: sussidi alle trivellazioni e alle fonti assimilate, gli extra-costi per le isole minori e quelli indiretti a sostegno delle aree geograficamente svantaggiate, le esenzioni per le imprese energivore e le esenzioni oneri di sistema, i finanziamenti pubblici e i contributi a impianti e centrali, le garanzie, i prestiti pubblici e le elusioni reti interne. Ci sono ancora detrazione e\/o riduzione di accise e sconti diretti e indiretti. Insomma un insieme di vantaggi che lo Stato riconosce e include nell\u2019attuale Piano Energia e Clima fermo al 2017.<\/p>\n<p>&nbsp;<\/p>\n<p>Oggetto di una campagna elettorale che non ha trovato alcuna attuazione e sostituibile con le prestanti fonti rinnovabili,<b> l\u2019eliminazione dei sussidi alle fonti fossili potrebbe avvenire tra qualche mese<\/b> con la pubblicazione del neo catalogo Energia e Clima.<\/p>\n<p>&nbsp;<\/p>\n<h3>Fonti fossili: i dati di AIEA e la proposta di Legambiente<\/h3>\n<p>&nbsp;<\/p>\n<p>Secondo l\u2019Agenzia Internazionale dell\u2019Energia (AIEA) <b>\u00e8 di almeno 300 miliardi di dollari il valore dei sussidi alle fonti fossili previsti nel 2017: <\/b>45% a sostegno del petrolio (circa 137 milioni di dollari), 23% al gas (quasi 57 miliardi di dollari) e 2 miliardi di dollari a sostegno del carbone. Cifre e percentuali in aumento rispetto al 2016.<\/p>\n<p>&nbsp;<\/p>\n<p>Le circa 28 voci di sussidio previste dall\u2019Italia rappresentano per Legambiente un elemento che danneggia il bilancio economico dello Stato a scapito di settori che meriterebbero maggiore attenzione e risorse economiche.<\/p>\n<p>Dunque l\u2019associazione propone nuove soluzioni: una road map per arrivare alla definitiva cancellazione dei sussidi alle fonti fossili nel 2025, la rimodulazione di almeno 4,5 miliardi di euro investiti e l\u2019aggiornamento del catalogo dei sussidi del prossimo Piano Energia e Clima al fine di spingere l\u2019innovazione e ridurre le emissioni ambientali.<\/p>\n<p>&nbsp;<\/p>\n<p>La rimodulazione dei sussidi permetterebbe di ricavare 4 miliardi di euro da investire nei settori ritenuti pi\u00f9 bisognosi: il servizio sanitario nazionale e il settore dell\u2019istruzione; 3 miliardi in pi\u00f9 in favore del fondo nazionale trasporti e ulteriori 3 miliardi di euro per la lotta al dissesto idrogeologico e per l\u2019adattamento ai cambiamenti climatici.<\/p>\n<p>&nbsp;<\/p>\n<p>In attesa della pubblicazione del prossimo Piano Energia e Clima <b>le aziende che beneficiano dei sussidi possono, e forse ancora per poco, approfittare degli sconti e dei benefici che le vengono riconosciuti.<\/b><\/p>\n<p>&nbsp;<\/p>\n<h3>Il sussidio per le imprese energivore<\/h3>\n<p>&nbsp;<\/p>\n<p>Con il Decreto Ministeriale del 27\/12\/2017 entrato in vigore il 1\u00b0 gennaio 2018 il Governo Italiano riconosce circa 1 miliardo e 700 milioni di euro alle imprese energivore considerate a maggior rischio concorrenza estera. Le imprese energivore (imprese ad alto consumo di energia elettrica) possono ricevere dallo Stato la possibilit\u00e0 di ridurre il costo degli oneri di sistema da pagare direttamente in fattura.<\/p>\n<p>&nbsp;<\/p>\n<p>Grazie all\u2019ultima riforma non \u00e8 pi\u00f9 cos\u00ec difficile usufruire di questi sconti in quanto la soglia di partecipazione all\u2019agevolazione \u00e8 stata abbassata a 1 GWh di energia elettrica all\u2019anno.<\/p>\n<p>A seguito della richiesta, appositamente effettuata nel periodo utile (prossimo settembre 2019) e attraverso il portale del CSEA, l\u2019impresa energivora potrebbe essere inclusa negli elenchi pubblicati dal CSEA e <b>ricavare l\u2019immediata possibilit\u00e0 di risparmiare pi\u00f9 di 30.000 \u20ac per i consumi registrati per il triennio 2016-2018.<\/b><\/p>\n<p>A fronte delle nuove proposte esposte da Legambiente e in vista delle possibili modifiche del Piano di Energia e Clima le imprese energivore interessate ai sussidi devono affrettarsi e richiedere la valutazione dei propri consumi.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Non perdere l\u2019occasione di risparmiare, compila il form!<\/b><\/p>","protected":false},"excerpt":{"rendered":"<p>Un dossier che propone la cancellazione dei sussidi alle fonti fossili.\u00a0A rischio finanziamenti e agevolazioni oil &amp; gas. &nbsp; Con l\u2019ultimo dossier sui sussidi alle fonti fossili Legambiente propone la cancellazione e la riduzione degli innumerevoli finanziamenti e sostegni che il governo italiano prevede a beneficio delle aziende italiane che impiegano fonti fossili nella loro [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14677,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-14676","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sostenibilita"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/posts\/14676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/comments?post=14676"}],"version-history":[{"count":0,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/posts\/14676\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/media\/14677"}],"wp:attachment":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/media?parent=14676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/categories?post=14676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/tags?post=14676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}