{"id":14728,"date":"2021-09-10T00:00:00","date_gmt":"2021-09-09T22:00:00","guid":{"rendered":"https:\/\/dev.goodata.eu\/una-strategia-sostenibile-per-il-futuro-delle-imprese-tecno-lancia-il-polo-italiano-della-sostenibilita\/"},"modified":"2024-10-02T12:57:15","modified_gmt":"2024-10-02T10:57:15","slug":"una-strategia-sostenibile-per-il-futuro-delle-imprese-tecno-lancia-il-polo-italiano-della-sostenibilita","status":"publish","type":"post","link":"https:\/\/www.goodata.eu\/en\/blog\/our-commitment-2\/una-strategia-sostenibile-per-il-futuro-delle-imprese-tecno-lancia-il-polo-italiano-della-sostenibilita\/","title":{"rendered":"Una strategia sostenibile per il futuro delle imprese: Tecno lancia il polo italiano della sostenibilit\u00e0"},"content":{"rendered":"<p><b>Favorire la crescita e la resilienza delle imprese con la sostenibilit\u00e0 e l\u2019innovazione, con competenza e nel rispetto della societ\u00e0.<\/b><\/p>\n<p>&nbsp;<\/p>\n<p>Grande successo per il primo appuntamento <i>Tecno Talks<\/i>, il ciclo di eventi con relatori internazionali sui temi della sostenibilit\u00e0 ambientale, sociale e finanziaria. <b>I <i>Tecno Talks<\/i> sono parte del nostro polo italiano della sostenibilit\u00e0.<\/b> Una nuova sfida che ci prepariamo ad affrontare in compagnia di un grande esperto della materia, Paolo Taticchi, che diventa ufficialmente membro del nostro Advisory Board per la sostenibilit\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<h2>Modelli d\u2019impresa sostenibili e innovativi: il polo italiano della sostenibilit\u00e0<\/h2>\n<p>&nbsp;<\/p>\n<p>Nasce il polo italiano della sostenibilit\u00e0, l\u2019hub dedicato alle imprese che intendono avviare strategie sostenibili per favorire la crescita e la resilienza aziendale.<\/p>\n<p>&nbsp;<\/p>\n<p>Il polo \u00e8 frutto della collaborazione tra pi\u00f9 partner, coordinati da Tecno; insieme per guidare le imprese verso nuovi modelli di business sostenibili e innovativi, all\u2019insegna di impegno ambientale, sociale ed esperienza digitale.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Parte integrante del progetto sono gli eventi di approfondimento, i <i>Tecno Talks<\/i>;<\/b> momenti di incontro e di confronto pensati per promuovere e diffondere la cultura della sostenibilit\u00e0 nelle imprese. I <i>Tecno Talks<\/i> sono caratterizzati dalla presenza di partner internazionali, esperti in diversi ambiti che aiuteranno i partecipanti a comprendere le peculiarit\u00e0, le opportunit\u00e0 e le difficolt\u00e0 dell\u2019approccio sostenibile.<\/p>\n<p>&nbsp;<\/p>\n<h3>Sostenibilit\u00e0 d\u2019impresa: via al primo dei <i>Tecno Talks<\/i><\/h3>\n<p>&nbsp;<\/p>\n<p>Lo scorso 26 luglio, nelle sale settecentesche del Palazzo Ischitella, sede storica della nostra azienda, si \u00e8 tenuto il convegno \u201c<i>Sostenibilit\u00e0 d\u2019impresa: investire ed essere competitivi, creando valore in un mondo che cambia<\/i>\u201d. <b>Il primo evento del ciclo di approfondimenti che lancia il neo polo italiano della sostenibilit\u00e0.<\/b><\/p>\n<p>&nbsp;<\/p>\n<p>Tra i relatori partner importanti, quali: Certiquality, V-Finance, Elite ed Assonime, ha contribuito a favorire il grande successo ottenuto, con la partecipazione di un pubblico vasto e attento, in presenza e in streaming.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019evento, moderato da Simone Filippetti del Sole 24 Ore, ha coinvolto pi\u00f9 relatori: Giovanni Lombardi, il nostro Presidente; Margherita Bianchini, vicedirettore di Assonime; Anna Lambiase, fondatrice e AD di V-Finance; Vincenzo Borrelli, industry manager builiding &amp; construction Certiquality; Marta Testi, AD Elite \u2013 Gruppo Euronext e Paolo Taticchi, professore in Strategy &amp; Sustainability precco UCL e Imperial College di Londra.<\/p>\n<p>&nbsp;<\/p>\n<p>Il convegno ha rappresentato anche l\u2019occasione per annunciare pubblicamente <b>l\u2019ingresso di Paolo Taticchi del nostro Advisory Board della sostenibilit\u00e0.<\/b><\/p>\n<p>&nbsp;<\/p>\n<h4>Il contesto: finanza sostenibile, evoluzione normativa ed esigenza di strumenti garantiti<\/h4>\n<p>&nbsp;<\/p>\n<p>L\u2019ultimo anno \u00e8 stato piuttosto complicato per le imprese, che hanno dovuto confrontarsi con le difficolt\u00e0 del Covid-19 e con le novit\u00e0 che quest\u2019ultimo ha contribuito ad accelerare.<\/p>\n<p>&nbsp;<\/p>\n<p>Parliamo della rapida trasformazione che la finanza sostenibile sta apportando all\u2019ecosistema del mercato dei capitali; dell\u2019evoluzione della normativa europea sui temi della sostenibilit\u00e0 d\u2019impresa; dell\u2019esigenza delle aziende di adottare strategie e strumenti utili a favorire la loro resilienza nel tempo.<\/p>\n<p>&nbsp;<\/p>\n<p><b>La costruzione di un approccio imprenditoriale sostenibile e innovativo \u00e8 la soluzione a tutto questo.<\/b> Lo stesso Paolo Taticchi afferma: \u201c<i>Sono convinto che la sostenibilit\u00e0, se affrontata in maniera corretta, pu\u00f2 essere una leva competitiva per le aziende<\/i>\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Ma la sostenibilit\u00e0, <b>l\u2019approccio sostenibile non va improvvisato.<\/b> Bisogna costruirlo con l\u2019ausilio di partner competenti in materia, <b>perch\u00e9 la strada della sostenibilit\u00e0 prima che intrapresa va compresa. <\/b>Solo le imprese che riusciranno realmente a comprendere le opportunit\u00e0 e i diversi ambiti di intervento della sostenibilit\u00e0 potranno generare valore e assicurarsi un posto in prima fila nel mercato internazionale del prossimo decennio.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Questo \u00e8 il nostro contesto.<\/b> Queste sono le imprese a cui ci rivolgiamo per sviluppare insieme un percorso volto alla sostenibilit\u00e0 aziendale, con servizi e prodotti sostenibili e digitali, trasparenti e garantiti.<\/p>\n<p>&nbsp;<\/p>\n<h2>Paolo Taticchi entra a far parte dell\u2019Advisory Board per la sostenibilit\u00e0 di Tecno<\/h2>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">\u201c<i>Tecno \u00e8 un\u2019azienda che da tempo guarda al futuro, investendo su due tematiche che sono chiave per la competitivit\u00e0 delle imprese, ovvero la trasformazione digitale e la trasformazione sostenibile, e le due cose sono ovviamente collegate<\/i>\u201d.<\/p>\n<p style=\"text-align: center;\">Paolo Taticchi<\/p>\n<p>&nbsp;<\/p>\n<p>Il professore in Strategy &amp; Sustainability presso UCL e Imperial College di Londra, il Deputy Director (vice preside) per gli MBA e le attivit\u00e0 globali accetta di entrare a far parte del nostro Advisory Board per la sostenibilit\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Insieme aiuteremo le aziende a sviluppare modelli di business compatibili con l\u2019Agenda 2030;<\/b> studieremo metodi efficaci e progetteremo prodotti capaci di generare valore per le imprese e per la societ\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<p>Con Paolo Taticchi continueremo a fortificare il nostro valore aggiunto, l\u2019approccio imprenditoriale. Continueremo dunque ad offrire non solo prodotti e servizi, bens\u00ec l\u2019opportunit\u00e0 di creare un percorso di crescita comune, essenziale in un ambito complesso come quello della sostenibilit\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<p>Guarda il <a href=\"https:\/\/www.youtube.com\/watch?v=oUhw4FnkAPI\" target=\"_blank\" rel=\"noopener nofollow\">video ufficiale<\/a> e seguici sui nostri canali social per restare informato sulle nostre iniziative e sui prossimi <i>Tecno Talks<\/i>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Favorire la crescita e la resilienza delle imprese con la sostenibilit\u00e0 e l\u2019innovazione, con competenza e nel rispetto della societ\u00e0. &nbsp; Grande successo per il primo appuntamento Tecno Talks, il ciclo di eventi con relatori internazionali sui temi della sostenibilit\u00e0 ambientale, sociale e finanziaria. I Tecno Talks sono parte del nostro polo italiano della sostenibilit\u00e0. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14731,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-14728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-il-nostro-impegno"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/posts\/14728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/comments?post=14728"}],"version-history":[{"count":0,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/posts\/14728\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/media\/14731"}],"wp:attachment":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/media?parent=14728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/categories?post=14728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/tags?post=14728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}