{"id":14834,"date":"2022-05-31T00:00:00","date_gmt":"2022-05-30T22:00:00","guid":{"rendered":"https:\/\/dev.goodata.eu\/bando-efficienza-energetica-piu-di-10-milioni-a-favore-delle-micro-e-piccole-imprese-lombarde\/"},"modified":"2024-10-03T15:44:21","modified_gmt":"2024-10-03T13:44:21","slug":"bando-efficienza-energetica-piu-di-10-milioni-a-favore-delle-micro-e-piccole-imprese-lombarde","status":"publish","type":"post","link":"https:\/\/www.goodata.eu\/en\/blog\/updates-and-announcements-2\/bando-efficienza-energetica-piu-di-10-milioni-a-favore-delle-micro-e-piccole-imprese-lombarde\/","title":{"rendered":"Bando efficienza energetica: pi\u00f9 di 10 milioni a favore delle micro e piccole imprese lombarde"},"content":{"rendered":"<p><b>Pacchetto energia: la Regione Lombardia stanzia pi\u00f9 di 10 milioni di euro per interventi di efficientamento energetico come sostegno ai settori del commercio, della ristorazione e dei servizi.<\/b><\/p>\n<p>&nbsp;<\/p>\n<p>Il pacchetto energia della Lombardia prevede tre bandi; il primo bando per l\u2019efficienza energetica \u00e8 rivolto ai settori del commercio, della ristorazione e dei servizi. La Regione Lombardia e il Sistema Camerale lombardo sostengono le micro e piccole imprese del territorio; un contributo a fondo perduto erogato per fronteggiare l\u2019aumento dei costi energetici che le imprese stanno affrontando, anche a causa della guerra in Ucraina.<\/p>\n<p>Gli altri due bandi usciranno a breve: uno a favore delle imprese artigiane e l\u2019altro per gli impianti natatori e del ghiaccio, per un totale complessivo di circa 65 milioni di euro.<\/p>\n<p>Vediamo di seguito in cosa consiste questo primo bando del pacchetto energia e quali sono le spese ammissibili per gli interventi di efficientamento energetico.<\/p>\n<p>&nbsp;<\/p>\n<h2>Agevolazione micro e piccole imprese: cosa prevede il bando<\/h2>\n<p>&nbsp;<\/p>\n<p>La prima agevolazione del pacchetto energia consiste in un<b> contributo a fondo perduto a parziale copertura delle spese sostenute dalle micro e piccole imprese<\/b> che posseggono determinati requisiti per poter accedere al bando.<\/p>\n<p><b>Le risorse stanziate ammontano complessivamente a 10.745.500,00 euro, <\/b>una parte \u00e8 a carico della Regione Lombardia e l\u2019altra a carico delle Camere di Commercio lombarde.<\/p>\n<p>La domanda di partecipazione va trasmessa esclusivamente in via telematica tramite il sito <a href=\"http:\/\/webtelemaco.infocamere.it\/newt\/public.htm\" target=\"_blank\" rel=\"noopener nofollow\">http:\/\/webtelemaco.infocamere.it<\/a><b> dalle ore 10.00 del 15 giugno 2022 fino alle ore 16.00 del 15 dicembre 2022.<\/b><\/p>\n<p>&nbsp;<\/p>\n<p>Il contributo \u00e8 assegnato con<b> procedura a sportello, secondo l\u2019ordine cronologico.<\/b><\/p>\n<p>Qualora vi sia un esaurimento delle risorse prima del 15 dicembre 2022 Unioncamere Lombardia (soggetto gestore del bando) provvede alla chiusura anticipata dei termini per la presentazione delle domande.<\/p>\n<p>&nbsp;<\/p>\n<h3>Beneficiari bando efficienza energetica: chi sono<\/h3>\n<p>&nbsp;<\/p>\n<p>Possono accedere al bando le <b>micro e piccole imprese le cui attivit\u00e0 rientrano nei settori del commercio e pubblici esercizi e servizi; <\/b>nello specifico vi rientrano:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>commercio al dettaglio;<\/li>\n<li>attivit\u00e0 dei servizi di ristorazione;<\/li>\n<li>attivit\u00e0 editoriali;<\/li>\n<li>attivit\u00e0 di servizi d\u2019informazione e altri servizi informatici;<\/li>\n<li>attivit\u00e0 immobiliari per conto terzi;<\/li>\n<li>attivit\u00e0 di supporto per le funzioni d&#8217;ufficio e altri servizi di supporto alle imprese;<\/li>\n<li>istruzione;<\/li>\n<li>attivit\u00e0 sportive di intrattenimento e divertimento;<\/li>\n<li>riparazione di computer e di beni per uso personale e per la casa.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3>Requisiti obbligatori: come accedere al bando<\/h3>\n<p>&nbsp;<\/p>\n<p>\u00c9 necessario che le imprese siano in possesso del codice ATECO primario o secondario riferito alla sede in cui sar\u00e0 effettuato l\u2019intervento; ci\u00f2 dalla data di presentazione della domanda fino all\u2019erogazione del contributo.<\/p>\n<p>I beneficiari devono essere in possesso dei seguenti <b>requisiti obbligatori:\u00a0<\/b><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>essere micro e piccole imprese;<\/li>\n<li>essere regolarmente iscritte e attive nel Registro delle imprese da almeno 12 mesi;<\/li>\n<li>essere in regola con il pagamento del diritto camerale;<\/li>\n<li>avere la sede operativa oggetto d\u2019intervento in Lombardia;<\/li>\n<li>avere legali rappresentanti, amministratori e soci per i quali non vi siano cause di divieto, di decadenza o di sospensione;<\/li>\n<li>non essere in stato di fallimento, di liquidazione anche volontaria, di amministrazione controllata, di concordato preventivo o situazione equivalente;<\/li>\n<li>non rientrare nelle esclusioni di cui all\u2019art. 1 del Regolamento Ue 1407\/2013;<\/li>\n<li>avere assolto gli obblighi contributivi (DURC).<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3>Spese ammissibili al contributo: quali sono<\/h3>\n<p>&nbsp;<\/p>\n<p>Il contributo a fondo perduto copre gli <b>investimenti per interventi di efficientamento energetico.<\/b> \u00c8 necessario che l\u2019<b>investimento minimo sia di almeno 4.000 euro;<\/b> il contributo <b>copre il 50% delle spese ammissibili <\/b>ed \u00e8 erogato per un <b>importo massimo di 30.000 euro.<\/b><\/p>\n<p>Ogni impresa pu\u00f2 presentare una sola richiesta di contributo.<\/p>\n<p>&nbsp;<\/p>\n<p>In fase di presentazione della domanda l\u2019impresa deve inoltrare la relazione di un tecnico iscritto al relativo ordine professionale. Nella relazione devono esserci i dettagli degli investimenti o delle soluzioni impiantistiche implementate; dalle spese deve essere possibile riscontrare il risparmio energetico che si \u00e8 ottenuto a seguito dell\u2019intervento di efficientamento energetico. <b>Ai fini del contributo sono accettate le seguenti spese:<\/b><\/p>\n<p>&nbsp;<\/p>\n<ol>\n<li>acquisto e installazione di collettori solari termici e\/o impianti di microgenerazione;<\/li>\n<li>impianti fotovoltaici per l\u2019autoproduzione di energia con fonti rinnovabili da utilizzare nel sito produttivo;<\/li>\n<li>acquisto e installazione di macchinari e attrezzature in sostituzione di quelli usati nel sito oggetto d\u2019intervento;<\/li>\n<li>acquisto e installazione di caldaie ad alta efficienza a condensazione, a biomassa o a pompe di calore in sostituzione delle vecchie caldaie;<\/li>\n<li>acquisto e installazione di raffrescatori\/raffredatori evaporativi portatili o fissi che non richiedono l\u2019utilizzo di fluidi refrigeranti;<\/li>\n<li>acquisto e installazione di sistemi di domotica per il risparmio energetico e di <a href=\"https:\/\/www.tecnosrl.it\/Monitoraggio-industriale\" target=\"_blank\" rel=\"noopener nofollow\">sistemi per il monitoraggio dei consumi energetici;<\/a><\/li>\n<li>acquisto e installazione di apparecchi LED a basso consumo a sostituzione di quelli tradizionali;<\/li>\n<li>costi per opere murarie e impiantistiche se correlati e funzionali all\u2019installazione dei beni oggetto di investimento;<\/li>\n<li>spese tecniche di consulenza per la realizzazione dell\u2019intervento.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><b>Le spese ammissibili sono quelle che rientrano nel periodo che va dal 26 aprile 2022 al 15 dicembre 2022;<\/b> far\u00e0 fede la data presente in fattura. Tutte le spese sono considerate al netto dell\u2019IVA e devono essere intestate al soggetto beneficiario.<\/p>\n<p>Le attrezzature tecnologiche sono ammesse anche se acquistate mediante leasing finanziario, nel rispetto di specifiche condizioni presenti nel bando.<\/p>\n<p>&nbsp;<\/p>\n<h2>Valutazione punteggio: efficienza energetica e certificazioni ambientali<\/h2>\n<p>&nbsp;<\/p>\n<p>Le domande presentate dalle micro e piccole imprese ricevono una valutazione sulla base di un punteggio che va da 0 a 100. <b>Per poter accedere al contributo \u00e8 necessario raggiungere un punteggio di 40 punti.<\/b><\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019istruttoria tecnica \u00e8 effettuata considerando i seguenti criteri di valutazione:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><b>coerenza con le finalit\u00e0 della misura oggetto del bando: <\/b>produzione dichiarata da fonti rinnovabili attraverso uno o pi\u00f9 interventi relativi ai primi due punti dell\u2019elenco delle spese ammissibili. Il possesso di questo requisito assegna 20 punti;<\/li>\n<li><b>capacit\u00e0 di generare efficienza energetica: <\/b>riduzione dichiarata in domanda dei consumi energetici complessivi del sito produttivo misurati in TEP evitati; ci\u00f2 grazie all\u2019acquisto e all\u2019installazione di macchinari rientranti tra il terzo e il settimo punto dell\u2019elenco delle spese ammissibili. Il punteggio assegnato va da 0 a 60 in base alla percentuale della riduzione;<\/li>\n<li><b>caratteristiche distintive delle imprese: <\/b>presenza di sistemi di certificazione ambientale e certificazioni energetiche al momento della presentazione della domanda. Il possesso di questo requisito assegna 20 punti.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>Efficienza energetica imprese: affidati al nostro team<\/h2>\n<p>&nbsp;<\/p>\n<p>Il nostro team ti accompagna nel percorso di efficienza energetica, consentendoti di partecipare al bando del pacchetto energia indetto dalla Regione Lombardia.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019<b>installazione di impianti fotovoltaici<\/b> e l\u2019<b>implementazione del nostro sistema di monitoraggio dei consumi energetici kontrolON<\/b> ti danno la possibilit\u00e0 di accedere al contributo a fondo perduto messo a disposizione per le imprese lombarde fino a 30.000 euro.<\/p>\n<p>&nbsp;<\/p>\n<p>Inoltre, <b>con le certificazioni ambientali aumenti la possibilit\u00e0 di accedere all\u2019agevolazione,<\/b> guadagnando un punteggio pi\u00f9 alto.<\/p>\n<p>&nbsp;<\/p>\n<p>Ti ricordiamo che il contributo \u00e8 assegnato secondo l\u2019ordine cronologico. <b>Non perdere questa opportunit\u00e0, contattaci adesso!<\/b><\/p>","protected":false},"excerpt":{"rendered":"<p>Pacchetto energia: la Regione Lombardia stanzia pi\u00f9 di 10 milioni di euro per interventi di efficientamento energetico come sostegno ai settori del commercio, della ristorazione e dei servizi. &nbsp; Il pacchetto energia della Lombardia prevede tre bandi; il primo bando per l\u2019efficienza energetica \u00e8 rivolto ai settori del commercio, della ristorazione e dei servizi. La [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14836,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[38],"tags":[],"class_list":["post-14834","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aggiornamenti-e-bandi"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/posts\/14834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/comments?post=14834"}],"version-history":[{"count":0,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/posts\/14834\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/media\/14836"}],"wp:attachment":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/media?parent=14834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/categories?post=14834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/tags?post=14834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}