{"id":14869,"date":"2024-01-10T00:00:00","date_gmt":"2024-01-09T23:00:00","guid":{"rendered":"https:\/\/dev.goodata.eu\/sostenibilita-aziendale-e-fattori-esg-la-guida-aggiornata-al-2024\/"},"modified":"2024-10-03T15:29:19","modified_gmt":"2024-10-03T13:29:19","slug":"sostenibilita-aziendale-e-fattori-esg-la-guida-aggiornata-al-2024","status":"publish","type":"post","link":"https:\/\/www.goodata.eu\/en\/blog\/sustainability-2\/sostenibilita-aziendale-e-fattori-esg-la-guida-aggiornata-al-2024\/","title":{"rendered":"Sostenibilit\u00e0 aziendale e fattori ESG: la guida aggiornata al 2024"},"content":{"rendered":"<p><a href=\"#uno\">L\u2019essenza di una strategia sostenibile esg-oriented<\/a><\/p>\n<p><a href=\"#due\">Integrare la sostenibilit\u00e0 nelle operazioni aziendali, cosa vuol dire?<\/a><\/p>\n<p><a href=\"#tre\">Il futuro delle imprese: sostenibilit\u00e0 e investimenti ESG<\/a><\/p>\n<p><a href=\"#quattro\">Perch\u00e9 un\u2019azienda dovrebbe puntare sugli investimenti ESG?<\/a><\/p>\n<p><a href=\"#cinque\">Chi si occupa della sostenibilit\u00e0 in azienda?<\/a><\/p>\n<p><a href=\"#sei\">Sostenibilit\u00e0 e brand reputation: dalla strategia alla comunicazione<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>In un contesto globale in cui le tematiche ambientali, la responsabilit\u00e0 sociale di aziende e individui e la gestione etica delle risorse sono diventati elementi essenziali del dibattito sulla sostenibilit\u00e0, adottare un approccio che implementa e contribuisce al benessere del pianeta rappresenta una condizione imprescindibile per raggiungere il progresso.<\/p>\n<p>&nbsp;<\/p>\n<p><a name=\"uno\"><\/a>Tra i principali attori coinvolti nel paradigma sostenibile troviamo proprio le aziende, sempre pi\u00f9 interessate dalle richieste del mercato, dalle normative e raccomandazioni delle organizzazioni mondiali e statali focalizzate sul contrasto al cambiamento climatico e volte al raggiungimento degli obiettivi definiti per la riduzione delle emissioni al 2030 e al 2050.<\/p>\n<p>Vediamo insieme in che modo le imprese possono affrontare la sostenibilit\u00e0 e perch\u00e9 \u00e8 importante agire in ambito ESG per la crescita aziendale.<\/p>\n<p>&nbsp;<\/p>\n<h2>L\u2019essenza di una strategia sostenibile esg-oriented<\/h2>\n<p>&nbsp;<\/p>\n<p>La sostenibilit\u00e0 aziendale rappresenta un approccio strategico e responsabile alla gestione delle attivit\u00e0 imprenditoriali, tenendo conto degli impatti economici, sociali e ambientali generati nel corso del ciclo di vita di un\u2019azienda.<\/p>\n<p>&nbsp;<\/p>\n<p>Ragionare in una prospettiva di lungo periodo, si traduce nell\u2019adottare soluzioni sostenibili tanto con riferimento ai modelli di governance adoperati, che con riguardo ai metodi di produzione.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Il ruolo delle imprese, in ambito sostenibile, \u00e8 duplice<\/b>: da un lato, queste sono soggetti responsabili dell\u2019impatto che la loro attivit\u00e0 produttiva ha sull\u2019ambiente e sulla societ\u00e0 circostanti; dall\u2019altro hanno il potenziale di diventare i principali promotori di una cultura sostenibile che guarda al futuro.<\/p>\n<p>&nbsp;<\/p>\n<p>Sulla base dei principi contenuti nell\u2019Agenda 2030 e degli Obiettivi di Sviluppo Sostenibile, la sostenibilit\u00e0 aziendale pu\u00f2 essere tradotta in strategie finalizzate all\u2019applicazione di criteri riconducibili al paradigma ESG, acronimo che sta ad indicare i tre pilastri della sostenibilit\u00e0, indispensabili per la transizione sostenibile delle aziende:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Environmental;<\/li>\n<li>Social;<\/li>\n<li><a name=\"due\"><\/a>Governance.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><a name=\"due\"><\/a>L\u2019adozione di un approccio sostenibile rende le aziende, gli stakeholder e tutti gli attori coinvolti un centro di creazione di valore per la societ\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<h2>Integrare la sostenibilit\u00e0 nelle operazioni aziendali, cosa vuol dire?<\/h2>\n<p>&nbsp;<\/p>\n<p>Integrare la sostenibilit\u00e0 nelle operazioni aziendali significa incorporare considerazioni economiche, sociali e ambientali nelle decisioni quotidiane e nelle pratiche di gestione di un&#8217;azienda.<\/p>\n<p>&nbsp;<\/p>\n<p>Le operazioni aziendali rappresentano il terreno fertile sul quale adoperare quotidianamente strategie sostenibili che afferiscono ai fattori ESG (Environmental, Social, Governance); un terreno su cui \u00e8 possibile intervenire con azioni concrete e vantaggiose:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><b>Analisi dell&#8217;impronta ambientale,<\/b> ovvero la valutazione e la misurazione dell\u2019impatto ambientale delle operazioni aziendali. Un esempio di questa tipologia di analisi \u00e8 la valutazione del carbon footprint di organizzazione, utile ad analizzare e quantificare le emissioni di CO2 prodotte dall\u2019impresa e connesse agli Scope 1, 2 e 3;<\/li>\n<\/ul>\n<ul>\n<li><b>Definizione chiara degli obiettivi di sostenibilit\u00e0<\/b>, effettuata in linea agli Obiettivi di Sviluppo Sostenibile presenti nell\u2019Agenda 2030 delle Nazioni Unite, e alle linee guida sulle best practices sostenibili definite a livello internazionale;<\/li>\n<\/ul>\n<ul>\n<li><b>Adozione di politiche di investimento <\/b>volte al miglioramento dell\u2019efficienza energetica, come l\u2019adozione di fonti di energia rinnovabile o l&#8217;implementazione di pratiche di gestione energetica;<\/li>\n<\/ul>\n<ul>\n<li><b>Creazione di una catena di approvvigionamento sostenibile<\/b>, che si traduce nella scelta di collaborare con fornitori che rispettino elevati standard di sostenibilit\u00e0, in modo da valutare e monitorare l&#8217;impatto ambientale lungo l&#8217;intera catena di fornitura;<\/li>\n<\/ul>\n<ul>\n<li><b>Integrazione della responsabilit\u00e0 sociale d&#8217;impresa<\/b> (CSR &#8211; Corporate Social Responsibility), ai fini del coinvolgimento della comunit\u00e0 locale e la promozione di una cultura aziendale etica;<\/li>\n<\/ul>\n<ul>\n<li><b>Comunicazione trasparente e chiara<\/b> delle politiche di sostenibilit\u00e0 adottate, attraverso la redazione di documenti volti alla rendicontazione delle proprie performance ESG (Report di Sostenibilit\u00e0, report CFO, ecc.), per coinvolgere eventuali stakeholder ed incrementare, allo stesso tempo, l\u2019affidabilit\u00e0 del brand per i consumatori;<\/li>\n<\/ul>\n<ul>\n<li><a name=\"tre\"><\/a><b>Coinvolgimento dei dipendenti <\/b>in tutte le iniziative di sostenibilit\u00e0, attraverso programmi di formazione ed eventi interni finalizzati alla valorizzazione dei lavoratori e alla crescita comune;<\/li>\n<li><b>Investimenti reali in progetti di ricerca e sviluppo<\/b> nell\u2019ambito dell\u2019innovazione sostenibile.<\/li>\n<\/ul>\n<p><b>\u00a0<\/b><\/p>\n<h3>Il futuro delle imprese: sostenibilit\u00e0 e investimenti ESG<\/h3>\n<p>&nbsp;<\/p>\n<p>Nel panorama aziendale sempre pi\u00f9 competitivo del 2024, l&#8217;attenzione verso la sostenibilit\u00e0 aziendale non \u00e8 pi\u00f9 una scelta, ma una necessit\u00e0 imperativa per le imprese che aspirano al successo a lungo termine.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Investire in sostenibilit\u00e0 rappresenta una mossa strategica<\/b>, in quanto consente di acquisire una visione di lungo periodo dell\u2019attivit\u00e0 aziendale e del suo impatto concreto.<\/p>\n<p>&nbsp;<\/p>\n<p>In questo contesto si inseriscono gli investimenti basati sui criteri ambientali, sociali e di governance (criteri ESG), diventati popolari a seguito della volont\u00e0 di un numero sempre maggiore di investitori di integrare la sostenibilit\u00e0 nelle decisioni finanziarie.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019acronimo \u201cESG\u201d sta ad indicare tre fattori:<\/p>\n<p>&nbsp;<\/p>\n<ol>\n<li><b>Ambientale (Environmental)<\/b>: riguarda le pratiche legate all&#8217;ambiente, come le emissioni di gas serra, l&#8217;uso sostenibile delle risorse, il cambiamento climatico e la gestione dei rifiuti;<\/li>\n<li><b>Sociale (Social)<\/b>: coinvolge aspetti sociali come la responsabilit\u00e0 sociale d&#8217;impresa, le pratiche di gestione dei dipendenti, la diversit\u00e0 e l&#8217;inclusione, la salute e la sicurezza dei lavoratori, nonch\u00e9 le relazioni con le comunit\u00e0 locali;<\/li>\n<li><b><a name=\"quattro\"><\/a>Governance (G):\u00a0<\/b>riguarda la struttura di governance aziendale, l&#8217;etica aziendale, la trasparenza, l&#8217;indipendenza del consiglio di amministrazione e la gestione dei conflitti di interesse.<\/li>\n<\/ol>\n<p>Gli investimenti ESG riguardano tutte le politiche di investimento inerenti ai tre fattori sopra menzionati.<\/p>\n<h3>Perch\u00e9 un\u2019azienda dovrebbe puntare sugli investimenti ESG?<\/h3>\n<p>&nbsp;<\/p>\n<p>I vantaggi connessi agli investimenti ESG sono numerosi, al punto da rendere questa tipologia di strumenti particolarmente attrattiva per gli investitori.\u00a0 Nello specifico, tra i vantaggi inerenti connessi agli investimenti ESG ci sono:<\/p>\n<p>&nbsp;<\/p>\n<p><b>La riduzione dei rischi.<\/b><br \/>\nGli investimenti ESG contribuiscono a identificare e mitigare i rischi associati a questioni ambientali, sociali e di governance che potrebbero influenzare negativamente le prestazioni finanziarie delle aziende.<\/p>\n<p>&nbsp;<\/p>\n<p><b>\u00a0Il rendimento finanziario a lungo termine.<\/b><br \/>\nLe aziende che adottano pratiche ESG solide sono maggiormente resilienti e gestiscono meglio i cambiamenti di mercato, favorendo un rendimento finanziario a lungo termine pi\u00f9 sostenibile.<\/p>\n<p>&nbsp;<\/p>\n<p><b>La stabilit\u00e0.\u00a0<\/b><\/p>\n<p>Una buona ed efficiente governance aziendale rappresenta, per gli investitori, una maggiore garanzia di stabilit\u00e0 sul lungo periodo; pertanto, le realt\u00e0 che rafforzano la propria governance in ottica sostenibile accrescono le proprie possibilit\u00e0 di conquista degli investitori.<\/p>\n<p>&nbsp;<\/p>\n<p><b>L\u2019efficienza operativa e il risparmio di costi.<\/b><\/p>\n<p>L&#8217;adozione di pratiche sostenibili spesso porta a una maggiore efficienza operativa e a un risparmio di costi a lungo termine. Investire in tecnologie e processi pi\u00f9 ecologici non solo riduce l&#8217;impatto ambientale, ma pu\u00f2 anche tradursi in risparmi energetici e costi operativi inferiori nel tempo.<\/p>\n<p>&nbsp;<\/p>\n<p><b>L\u2019attrazione e la fidelizzazione dei talenti.<\/b><\/p>\n<p>Le nuove generazioni di talenti sono fortemente orientate ai valori. Un impegno chiaro verso la sostenibilit\u00e0 \u00e8 un potente strumento di attrazione e fidelizzazione dei dipendenti. <a name=\"cinque\"><\/a>Le aziende che dimostrano una responsabilit\u00e0 sociale e ambientale attirano professionisti motivati, contribuendo a creare una cultura aziendale impegnata e innovativa.<\/p>\n<div><\/div>\n<h2>Chi si occupa della sostenibilit\u00e0 in azienda?<\/h2>\n<div><\/div>\n<div>\n<div>Sono sempre pi\u00f9 numerose le realt\u00e0 aziendali che integrano nel proprio organico specifiche figure che si occupano di sostenibilit\u00e0 aziendale.<\/div>\n<div><\/div>\n<div>Si tratta di figure professionali che hanno il compito principale di integrare pratiche e politiche sostenibili all\u2019interno dell\u2019organizzazione , attraverso l\u2019elaborazione di strategie e la promozione di una cultura orientata al rispetto dell\u2019ambiente.<\/div>\n<div><\/div>\n<div>Il numero di profili professionali pu\u00f2 variare a seconda delle dimensioni e della struttura dell\u2019organizzazione. Tuttavia, tra i ruoli chiave che si occupano di sostenibilit\u00e0 aziendale troviamo:<\/div>\n<div><\/div>\n<ul>\n<li><b>Il Sustainability Manager o ESG Manager<\/b>: figura responsabile della definizione e dell\u2019implementazione delle strategie aziendali orientate alla sostenibilit\u00e0. Quella del Sustainability Manager \u00e8 una figura trasversale, che opera in aree come la comunicazione aziendale, l\u2019efficienza energetica, la responsabilit\u00e0 sociale d\u2019impresa e il controllo dell\u2019impatto dei processi produttivi. Tra le responsabilit\u00e0 principali del Sustainability Manager c\u2019\u00e8 la definizione degli obiettivi a lungo termine che guidano l\u2019intera organizzazione aziendale;<\/li>\n<li><b>L\u2019Analista di sostenibilit\u00e0<\/b>: ruolo preposto alla raccolta di dati ed indicatori per il monitoraggio e la valutazione dell\u2019impatto ambientale, sociale ed economico di un\u2019azienda. Quella dell\u2019analista di sostenibilit\u00e0 \u00e8 una figura che contribuisce allo sviluppo di opportunit\u00e0 di miglioramento dei processi aziendali in linea con gli obiettivi sostenibili a lungo termine;<\/li>\n<\/ul>\n<div><\/div>\n<ul>\n<li><b>L\u2019HSE Manager<\/b>, ovvero il Responsabile Ambiente, Salute e Sicurezza: figura preposta al monitoraggio ed implementazione di politiche e pratiche che riducono l\u2019impatto ambientale e garantiscono un ambiente di lavoro sicuro e salutare. Si tratta di una figura di supporto tanto in fase strategica, quanto in fase operativa;<\/li>\n<\/ul>\n<div><\/div>\n<ul>\n<li><b>Il Corporate Social Responsibility Manager<\/b>: figura che si occupa del conseguimento degli obiettivi di sostenibilit\u00e0 e responsabilit\u00e0 sociale dell\u2019azienda.\u00a0<a name=\"sei\"><\/a>Questo profilo professionale \u00e8 responsabile della promozione e del mantenimento di una cultura aziendale attenta e sensibile alle tematiche sostenibili e socialmente responsabili.\u00a0Il CSR Manager, infatti, predispone iniziative di natura filantropica, culturale ed etica volte alla creazione di valore per la comunit\u00e0.<\/li>\n<\/ul>\n<\/div>\n<div style=\"font-weight: bold;\"><\/div>\n<div>\n<h2>Sostenibilit\u00e0 e brand reputation: dalla strategia alla comunicazione<\/h2>\n<p>La sostenibilit\u00e0 aziendale \u00e8 un corollario di principi, pratiche e obiettivi che un\u2019impresa sceglie di adottare nel momento in cui si fa portavoce di valori legati alla societ\u00e0 e all\u2019ambiente, ed \u00e8 per questa ragione strettamente legata alla reputazione di un brand.<\/p>\n<p>&nbsp;<\/p>\n<p>Misurare l\u2019impatto della propria attivit\u00e0 produttiva sull\u2019ambiente e la societ\u00e0 circostanti e <b>diventare concreti portavoce di un approccio nuovo<\/b> al modo di fare impresa, produce un duplice vantaggio per le aziende:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>una reputazione, a livello di brand, in linea con un sistema di valori dal forte impatto etico;<\/li>\n<li>un incremento di fiducia da parte dei consumatori, pi\u00f9 propensi ad affidarsi ad un brand che rispetti valori sostenibili condivisi dall\u2019intera collettivit\u00e0.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>\u00c9 opportuno precisare che, per poter incrementare la brand reputation di un\u2019impresa in ottica sostenibile, \u00e8 necessario intraprendere delle <b>azioni concrete e quotidiane<\/b> per ridurre l\u2019impatto ambientale della propria attivit\u00e0 produttiva ed incrementare strategie di governance sostenibile.<\/p>\n<p>&nbsp;<\/p>\n<p>Le strategie sostenibili adottate e la comunicazione trasparente sono elementi che migliorano significativamente l\u2019immagine aziendale, sia in ottica sostenibile che pi\u00f9 generale.<\/p>\n<p>&nbsp;<\/p>\n<p>Chi interviene con azioni efficaci a favore dell\u2019ambiente, della societ\u00e0 e delle persone <b>deve informare il proprio pubblico<\/b> di quanto fatto per evidenziare il proprio impegno, e per farlo pu\u00f2 avvalersi di professionisti capaci di valorizzare gli sforzi compiuti con documenti di sostenibilit\u00e0 redatti secondo standard riconosciuti a livello internazionale e una comunicazione ESG trasparente ed efficace.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Investire sulla sostenibilit\u00e0 vuol dire investire nel futuro.<br \/>\n<\/b><\/p>\n<p><b>Scopri il nostro metodo.<\/b><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>L\u2019essenza di una strategia sostenibile esg-oriented Integrare la sostenibilit\u00e0 nelle operazioni aziendali, cosa vuol dire? Il futuro delle imprese: sostenibilit\u00e0 e investimenti ESG Perch\u00e9 un\u2019azienda dovrebbe puntare sugli investimenti ESG? Chi si occupa della sostenibilit\u00e0 in azienda? Sostenibilit\u00e0 e brand reputation: dalla strategia alla comunicazione &nbsp; In un contesto globale in cui le tematiche ambientali, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14870,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-14869","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sostenibilita"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/posts\/14869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/comments?post=14869"}],"version-history":[{"count":0,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/posts\/14869\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/media\/14870"}],"wp:attachment":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/media?parent=14869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/categories?post=14869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/tags?post=14869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}