{"id":14896,"date":"2024-02-16T00:00:00","date_gmt":"2024-02-15T23:00:00","guid":{"rendered":"https:\/\/dev.goodata.eu\/in-cosa-consiste-la-corporate-social-responsibility-e-che-ruolo-svolge-in-azienda\/"},"modified":"2024-10-03T15:24:18","modified_gmt":"2024-10-03T13:24:18","slug":"in-cosa-consiste-la-corporate-social-responsibility-e-che-ruolo-svolge-in-azienda","status":"publish","type":"post","link":"https:\/\/www.goodata.eu\/en\/blog\/sustainability-2\/in-cosa-consiste-la-corporate-social-responsibility-e-che-ruolo-svolge-in-azienda\/","title":{"rendered":"In cosa consiste la Corporate Social Responsibility e che ruolo svolge in azienda?"},"content":{"rendered":"<p>La Corporate Social Responsibility (CSR), o Responsabilit\u00e0 Sociale d\u2019Impresa, \u00e8 stata definita dalla Comunit\u00e0 Europea, all\u2019interno del Libro Verde, come \u201cl\u2019integrazione su base volontaria, da parte delle imprese, delle preoccupazioni sociali e ambientali nelle loro operazioni commerciali e nei rapporti con le parti interessate\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Quello della CSR \u00e8 un concetto che si \u00e8 evoluto nel tempo passando dal riferimento al rapporto tra impresa e stakeholder in termini di fiducia e reputazione aziendale, a quello di impegno concreto posto in essere dall\u2019azienda in ambito sociale ed ambientale.<\/p>\n<p>&nbsp;<\/p>\n<p>Questa tipologia di Responsabilit\u00e0 d\u2019Impresa viene comunemente definita \u201csociale\u201d perch\u00e9 \u00e8 riferita a logiche che vanno al di l\u00e0 degli obiettivi di massimizzazione del profitto. I principi della Corporate Social Responsibility includono: la promozione della sostenibilit\u00e0 ambientale, il rispetto dei diritti umani, la trasparenza, la conformit\u00e0 alle leggi e normative, il coinvolgimento delle parti interessate e il miglioramento delle condizioni sociali ed economiche delle comunit\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<p>In questo articolo approfondiamo insieme il ruolo della CSR nelle aziende, che tipo di effetti produce in termini di reputazione d&#8217;impresa e quali sono le migliori strategie per comunicare questi principi a consumatori e stakeholder.<\/p>\n<div><\/div>\n<h2>La direttiva CSRD e la Responsabilit\u00e0 Sociale d\u2019Impresa<\/h2>\n<p>&nbsp;<\/p>\n<p>La Corporate Social Responsibility comprende al suo interno numerose pratiche sostenibili che attengono ai fattori Environmental, Social e Governance, come: la riduzione delle emissioni di gas a effetto serra, l\u2019adozione di politiche di lavoro equo, il sostegno alle comunit\u00e0 locali attraverso programmi di finanziamento del terzo settore e l\u2019adozione di politiche di trasparenza e reporting circa gli impatti dell\u2019attivit\u00e0 svolta.<\/p>\n<p>&nbsp;<\/p>\n<p>Sul tema della Responsabilit\u00e0 Sociale d\u2019Impresa, e della sua integrazione all\u2019interno dei fattori ESG, sono numerose le iniziative legislative sul tema: la ISO 26000, la Direttiva europea sull\u2019obbligo di DNF (Dichiarazione Non Finanziaria) e la pi\u00f9 recente Corporate Sustainability Reporting Directive (CSRD).<\/p>\n<p>&nbsp;<\/p>\n<p>La direttiva CSRD, entrata in vigore il 5 gennaio 2023, ha rafforzato le regole inerenti agli obblighi di rendicontazione e di comunicazione della responsabilit\u00e0 sociale per le imprese con pi\u00f9 di 500 dipendenti, le banche, le assicurazioni e le societ\u00e0 quotate di qualsiasi dimensione (eccezion fatta per le micro imprese), per un totale di circa 50mila aziende.<\/p>\n<p>&nbsp;<\/p>\n<p>I parametri a cui le imprese dovranno fare riferimento sono <b><a href=\"https:\/\/www.tecnosrl.it\/blog\/Sostenibilit%C3%A0\/Standard-ESRS-e-reporting-aziendale:-novit%C3%A0-per-il-2024\" target=\"_blank\" rel=\"noopener nofollow\">gli standard ESRS<\/a><\/b> emessi dall\u2019European Financial Reporting Advisory Group (EFRAG) e menzionati all\u2019interno della direttiva come punto di riferimento per valutare il rispetto degli obblighi ESG delle imprese coinvolte.<\/p>\n<p>&nbsp;<\/p>\n<p>In un\u2019ottica di Responsabilit\u00e0 Sociale d\u2019Impresa \u00e8 necessario che le aziende adottino una cultura di impegno e trasparenza sull\u2019impatto sociale ed ambientale della propria attivit\u00e0, con un focus sui seguenti aspetti:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Questioni ambientali;<\/li>\n<li>Questioni sociali, di welfare e benessere dei lavoratori;<\/li>\n<li>Rispetto dei diritti umani;<\/li>\n<li>Contrasto alla corruzione;<\/li>\n<li>Promozione di inclusivit\u00e0 ed inclusione.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><b>Il rispetto di questi principi deve essere rendicontato e reso accessibile al pubblico<\/b>, attraverso strumenti di analisi e valutazione delle performance ESG come il Report o il Bilancio di Sostenibilit\u00e0.<\/p>\n<div><\/div>\n<h3>Che impatto ha la CSR sulla comunit\u00e0 esterna e sulla reputazione aziendale?<\/h3>\n<p>&nbsp;<\/p>\n<p>Il concetto alla base della Corporate Social Responsibility (CSR) sottolinea che la sola ricerca di profitto non \u00e8 pi\u00f9 adeguata per garantire la sopravvivenza di un&#8217;organizzazione.<\/p>\n<p>&nbsp;<\/p>\n<p>Dal momento in cui la CSR \u00e8 strettamente legata agli stakeholder, i quali hanno un ruolo cruciale nella creazione e nel mantenimento della reputazione aziendale, diventa imprescindibile adottare politiche e pratiche di CSR per preservare, su diversi fronti, <b>la reputazione dell&#8217;azienda, la quale \u00e8 direttamente connessa alle relazioni sociali e alle attivit\u00e0 di comunicazione<\/b>.<\/p>\n<p>&nbsp;<\/p>\n<p>La reputazione aziendale rappresenta un elemento centrale nella gestione dei rapporti che l\u2019azienda intrattiene con la societ\u00e0 esterna: sia con riferimento a potenziali e attuali investitori, che rispetto a utenti finali, consumatori e potenziali candidati.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Una politica trasparente e chiara circa le iniziative di Responsabilit\u00e0 Sociale di un\u2019impresa \u00e8 il modo pi\u00f9 immediato di trasmissione esterna dei valori aziendali<\/b>: fattore che crea una solida reputazione aziendale, contribuisce all\u2019incremento dei profitti e fidelizza il pubblico di investitori e consumatori.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00c8 necessario considerare le pratiche di CSR come un investimento a lungo termine che l\u2019impresa sceglie di fare per migliorare la propria reputazione e per integrare o migliorare il fattore Social all\u2019interno delle operazioni aziendali, con il fine di creare un clima positivo e attento alle tematiche sostenibili.<\/p>\n<p>&nbsp;<\/p>\n<p>In buona sostanza, sono proprio le iniziative afferenti alla Corporate Social Responsibility il principale driver per la<b> creazione di valore<\/b> in azienda, perch\u00e9 racchiudono l\u2019impegno in ambito sostenibile, sociale e di governance che l\u2019azienda intraprende.<\/p>\n<p>&nbsp;<\/p>\n<h2>Come comunicare la responsabilit\u00e0 sociale di un\u2019impresa?<\/h2>\n<p>&nbsp;<\/p>\n<p>Con la rapida evoluzione della Corporate Social Responsibility (CSR) e la crescente necessit\u00e0 di agire conformemente agli standard istituzionali e socio-ambientali, sono stati sviluppati numerosi strumenti che agevolano l&#8217;attuazione di politiche etiche, consentono il monitoraggio dei risultati e, soprattutto, <b>offrono alle aziende la possibilit\u00e0 di dimostrare esternamente che le loro azioni sono in linea con quanto affermano di praticare.<\/b><\/p>\n<p>&nbsp;<\/p>\n<p>Tra questi strumenti troviamo i documenti di reportistica sulle performance, gli obiettivi e i risultati ESG conseguiti dalle aziende, come il <b><a href=\"https:\/\/www.tecnosrl.it\/blog\/Sostenibilit%C3%A0\/Bilancio-di-Sostenibilit%C3%A0:-cos%E2%80%99%C3%A8-e-a-chi-%C3%A8-rivolto\" target=\"_blank\" rel=\"noopener nofollow\">Report di Sostenibilit\u00e0 e il Bilancio di Sostenibilit\u00e0<\/a><\/b> di fondamentale importanza anche per una questione di gestione di rapporti con gli stakeholder, che grazie a questi strumenti hanno a disposizione un pool di fonti da cui attingere per reperire informazioni sull\u2019impresa.<\/p>\n<p>&nbsp;<\/p>\n<p>Per comunicare la Corporate Social Responsibility l\u2019azienda pu\u00f2 anche ricorrere a strumenti pi\u00f9 tradizionali, che hanno il fine di mostrare al pubblico quali sono i principi su cui si fonda l\u2019intera organizzazione, ad esempio:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><b>Carta dei valori<\/b>: contenente la vision e la mission; un documento in cui si racchiudono gli obiettivi strategici a lungo termine;<\/li>\n<li><b>Codice etico<\/b>: un documento aziendale nel quale appaiono i doveri morali dell\u2019impresa e i diritti dei collaboratori. La sua utilit\u00e0 \u00e8 quella di definire e illustrare la responsabilit\u00e0 etica-sociale di ogni membro dell\u2019organizzazione. I principi generali contenuti nel Codice Etico sono equit\u00e0, trasparenza, onest\u00e0, tutela dell\u2019ambiente e della persona;<\/li>\n<li>Altri strumenti di corporate communication, come le iniziative formative svolte, o le campagne di sensibilizzazione online e offline.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Nella comunicazione della responsabilit\u00e0 sociale di un\u2019impresa \u00e8 importante, nonch\u00e9 obbligatorio per legge, che le informazioni fornite siano:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><b>Veritiere e non ingannevoli<\/b>, quindi attinenti ad iniziative realmente poste in essere dall\u2019impresa;<\/li>\n<li><b>Coerenti rispetto agli obiettivi Environmental, Social e Governance<\/b> che l\u2019azienda ha stabilito.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Inoltre, la comunicazione della sostenibilit\u00e0 aziendale, e di tutto quello che rientra nella Responsabilit\u00e0 Sociale, deve essere strutturata in modo tale che le informazioni siano rese accessibili al pubblico esterno, e quindi siano di chiara comprensibilit\u00e0 e fruibilit\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<h3>Accelera la transizione verso un modello di responsabilit\u00e0 sociale d\u2019impresa con Tecno<\/h3>\n<h3><\/h3>\n<p>Compreso il ruolo centrale ricoperto dalla Corporate Social Responsibility all\u2019interno delle dinamiche ESG, \u00e8 opportuno strutturare un modello della stessa che possa durare nel tempo.<\/p>\n<p>&nbsp;<\/p>\n<p>Un modello d\u2019impresa improntato sulla diversit\u00e0 e l\u2019inclusione, il rispetto degli obblighi di rendicontazione sostenibile e la contribuzione allo sviluppo sociale ed ambientale di persone, dipendenti aziendali e territorio.<\/p>\n<p>&nbsp;<\/p>\n<p>In Tecno affianchiamo le imprese nel loro percorso di crescita sostenibile con percorsi su misura, fatti di azioni concrete, obiettivi chiari e risultati misurabili.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Incrementa la Responsabilit\u00e0 Sociale della tua impresa con noi.\u00a0<\/b><\/p>","protected":false},"excerpt":{"rendered":"<p>La Corporate Social Responsibility (CSR), o Responsabilit\u00e0 Sociale d\u2019Impresa, \u00e8 stata definita dalla Comunit\u00e0 Europea, all\u2019interno del Libro Verde, come \u201cl\u2019integrazione su base volontaria, da parte delle imprese, delle preoccupazioni sociali e ambientali nelle loro operazioni commerciali e nei rapporti con le parti interessate\u201d. &nbsp; Quello della CSR \u00e8 un concetto che si \u00e8 evoluto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14897,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-14896","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sostenibilita"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/posts\/14896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/comments?post=14896"}],"version-history":[{"count":0,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/posts\/14896\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/media\/14897"}],"wp:attachment":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/media?parent=14896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/categories?post=14896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/tags?post=14896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}