{"id":14898,"date":"2024-02-22T00:00:00","date_gmt":"2024-02-21T23:00:00","guid":{"rendered":"https:\/\/dev.goodata.eu\/il-greenwashing-come-ostacolo-alla-csr-corporate-social-responsibility\/"},"modified":"2025-06-30T17:53:50","modified_gmt":"2025-06-30T15:53:50","slug":"il-greenwashing-come-ostacolo-alla-csr-corporate-social-responsibility","status":"publish","type":"post","link":"https:\/\/www.goodata.eu\/en\/blog\/sustainability-2\/il-greenwashing-come-ostacolo-alla-csr-corporate-social-responsibility\/","title":{"rendered":"Il greenwashing come ostacolo alla (CSR) Corporate Social Responsibility"},"content":{"rendered":"<p>L\u2019attenzione alla sostenibilit\u00e0 ambientale e sociale ha assunto un ruolo centrale nelle discussioni pubbliche e nelle scelte strategiche adottate dalle imprese.<\/p>\n<p>&nbsp;<\/p>\n<p>Insieme alla considerazione sugli impatti ambientali di prodotti ed organizzazioni, nel corso degli anni \u00e8 emerso un fattore essenziale nel dibattito sul rispetto dell\u2019ambiente: <b>la comunicazione delle informazioni riguardanti la sostenibilit\u00e0; <\/b>parte integrante della responsabilit\u00e0 sociale d\u2019impresa.<\/p>\n<p>&nbsp;<\/p>\n<p>In questo contenuto esploreremo un fenomeno che interessa questo tipo di comunicazione, ovvero il greenwashing: le sue cause, gli effetti e le strategie per contrastarlo. Inoltre, approfondiremo il concetto di responsabilit\u00e0 sociale d&#8217;impresa, analizzando come le imprese possono autenticamente impegnarsi per la sostenibilit\u00e0 e il benessere sociale, andando oltre le mere dichiarazioni di intenti e dimostrando un vero impegno verso un cambiamento positivo.<\/p>\n<p>&nbsp;<\/p>\n<h2>Le pratiche di greenwashing e i rischi connessi<\/h2>\n<p>&nbsp;<\/p>\n<p>Il greenwashing si configura come <b>un&#8217;azione distorta e fuorviante<\/b> attraverso la quale un&#8217;organizzazione o un&#8217;impresa cerca di presentarsi come pi\u00f9 sostenibile e rispettosa delle normative e delle pratiche sostenibili di quanto effettivamente sia.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00c8 una condotta che si colloca in una zona grigia, tra la pubblicit\u00e0 fuorviante e le pratiche poco etiche legate alla <b><a href=\"https:\/\/www.tecnosrl.it\/blog\/Sostenibilit%C3%A0\/In-cosa-consiste-la-Corporate-Social-Responsibility-e-che-ruolo-svolge-in-azienda\" target=\"_blank\" rel=\"noopener nofollow\">Responsabilit\u00e0 Sociale d\u2019Impresa<\/a><\/b>, e pu\u00f2 riguardare informazioni inerenti a:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Dichiarazioni false circa l\u2019impatto ambientale dei prodotti e dell\u2019organizzazione;<\/li>\n<li>Uso improprio di certificazioni e marchi ecologici sulle etichette;<\/li>\n<li>Iniziative di Responsabilit\u00e0 Sociale d&#8217;Impresa (CSR) pubblicizzate con il solo scopo di distogliere l\u2019attenzione da pratiche poco sostenibili;<\/li>\n<li>Esaltazione di qualit\u00e0 sostenibili dei prodotti o del loro ciclo di vita, non veritiera o volta a mascherare gli impatti ambientali della produzione, uso e smaltimento degli stessi;<\/li>\n<li>Mancanza di chiarezza sulla destinazione degli investimenti in progetti sostenibili;<\/li>\n<li>Uso di immagini o di messaggi fuorvianti su piattaforme digitali per promuovere l&#8217;immagine &#8220;green&#8221; di un&#8217;azienda, insieme alla creazione di narrazioni ingannevoli attraverso strategie di marketing digitale.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Mettere in atto queste condotte \u00e8 una mossa dannosa per l\u2019immagine aziendale e per l\u2019organizzazione nel suo insieme, incidendo in maniera significativa sull\u2019affidabilit\u00e0 dell\u2019impresa, agli occhi di stakeholder e consumatori finali.<\/p>\n<p>&nbsp;<\/p>\n<p>I danni all\u2019immagine aziendale non sono i soli tra i <b>rischi connessi al greenwashing<\/b>; ci sono anche:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Le eventuali segnalazioni, e sanzioni amministrative e pecuniarie da parte di pubbliche autorit\u00e0 o Enti di certificazione;<\/li>\n<li>La possibile esclusione da bandi di finanziamento riservati ad imprese a basso impatto ambientale;<\/li>\n<li>Il calo dell\u2019interesse dei consumatori e dunque delle vendite;<\/li>\n<li>La perdita di potenziali ed attuali partnership.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Per evitare che un\u2019impresa adotti pratiche\u00a0 di greenwashing ed incorra in questi rischi \u00e8 necessario adottare un approccio che comunichi e trasmetta in maniera chiara e trasparente l\u2019impegno ESG dell\u2019azienda.<\/p>\n<div><\/div>\n<h3>\u00a0Il ruolo della Corporate Social Responsibility nel contrasto al fenomeno del Greenwashing<\/h3>\n<p>&nbsp;<\/p>\n<p>Le imprese che integrano i fattori ESG nelle strategie aziendali sono consapevoli dell\u2019importanza della <b>Responsabilit\u00e0 Sociale d\u2019Impresa.<\/b><\/p>\n<p>&nbsp;<\/p>\n<p>La Corporate Social Responsibility (CSR) contribuisce a contrastare il fenomeno del greenwashing, promuovendo pratiche aziendali autenticamente coerenti rispetto ai criteri Environmental, Social e Governance.<\/p>\n<p>&nbsp;<\/p>\n<p>Tra i fattori che rientrano nella CSR, infatti, troviamo:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><b>Trasparenza e accountability<\/b>: le aziende che investono in iniziative ESG sono solitamente pi\u00f9 trasparenti riguardo alle pratiche e agli impatti ambientali e sociali delle loro attivit\u00e0;<\/li>\n<li><b>Misurazione e monitoraggio<\/b>: le aziende impegnate nella CSR implementano i sistemi di misurazione, monitoraggio e reporting delle proprie prestazioni ambientali e sociali, seguendo gli standard previsti da norme nazionali ed internazionali, come la direttiva CSR. Questi strumenti forniscono dati affidabili e verificabili che possono essere utilizzati per dimostrare il reale impatto dei prodotti, delle organizzazioni e della governance aziendale;<\/li>\n<li><b>Coinvolgimento delle parti interessate<\/b>: le aziende che promuovono la propria responsabilit\u00e0 sociale coinvolgono attivamente le parti interessate nel processo decisionale aziendale, inclusi i consumatori, gli investitori, le comunit\u00e0 locali e le organizzazioni non governative.<br \/>\nUn coinvolgimento che favorisce la trasparenza, la responsabilit\u00e0,\u00a0 la circolazione delle informazioni allontanando tutti rischi connessi.<\/li>\n<\/ul>\n<h3>Come evitare il greenwashing con un piano di comunicazione ESG<\/h3>\n<p>&nbsp;<\/p>\n<p>Il fenomeno del greenwashing \u00e8 oggetto di iniziative legislative di fama internazionale, come la recente direttiva europea sui Green Claim.<\/p>\n<p>&nbsp;<\/p>\n<p>Per quanto si tratti di condotte oramai conosciute alla gran parte delle aziende, evitare di incorrere in queste pratiche non \u00e8 semplice: il rischio di trasmettere informazioni in maniera non adeguata \u00e8 alto, sia con riferimento a contenuti tecnici che a contenuti pi\u00f9 generici.<\/p>\n<p>&nbsp;<\/p>\n<p>Una buona strategia per contrastare il greenwashing \u00e8 quella di costruire un piano di comunicazione ESG: trasparente, completo e in linea con gli obiettivi sostenibili perseguiti dalla tua azienda.<\/p>\n<p>&nbsp;<\/p>\n<p><b><i>Insieme possiamo definire un piano di comunicazione capace di trasmettere l\u2019impegno aziendale in maniera chiara e adatta al tuo pubblico, evitando il rischio di fornire informazioni fuorvianti.\u00a0<\/i><\/b><\/p>","protected":false},"excerpt":{"rendered":"<p>L\u2019attenzione alla sostenibilit\u00e0 ambientale e sociale ha assunto un ruolo centrale nelle discussioni pubbliche e nelle scelte strategiche adottate dalle imprese. &nbsp; Insieme alla considerazione sugli impatti ambientali di prodotti ed organizzazioni, nel corso degli anni \u00e8 emerso un fattore essenziale nel dibattito sul rispetto dell\u2019ambiente: la comunicazione delle informazioni riguardanti la sostenibilit\u00e0; parte integrante [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":83944,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-14898","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sostenibilita"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/posts\/14898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/comments?post=14898"}],"version-history":[{"count":0,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/posts\/14898\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/media\/83944"}],"wp:attachment":[{"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/media?parent=14898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/categories?post=14898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.goodata.eu\/en\/wp-json\/wp\/v2\/tags?post=14898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}